{"id":3101,"date":"2011-09-01T00:00:00","date_gmt":"2011-09-01T00:00:00","guid":{"rendered":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021.jpg"},"modified":"2011-09-01T00:00:00","modified_gmt":"2011-09-01T00:00:00","slug":"kuca-fudbala-0021","status":"inherit","type":"attachment","link":"https:\/\/mppjedinstvo.co.rs\/rs\/kuca-fudbala-0021\/","title":{"rendered":"kuca-fudbala-0021"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021.jpg'><img width=\"225\" height=\"300\" src=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-225x300.jpg 225w, https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021.jpg 450w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":600,"file":"2011\/09\/kuca-fudbala-0021.jpg","filesize":82671,"sizes":{"medium":{"file":"kuca-fudbala-0021-225x300.jpg","width":225,"height":300,"filesize":25566,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-225x300.jpg"},"thumbnail":{"file":"kuca-fudbala-0021-150x150.jpg","width":150,"height":150,"filesize":16789,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-150x150.jpg"},"post-thumbnail":{"file":"kuca-fudbala-0021-450x288.jpg","width":450,"height":288,"filesize":39555,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-450x288.jpg"},"large-feature":{"file":"kuca-fudbala-0021-450x288.jpg","width":450,"height":288,"filesize":39555,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-450x288.jpg"},"small-feature":{"file":"kuca-fudbala-0021-225x300.jpg","width":225,"height":300,"filesize":25566,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021-225x300.jpg"},"full":{"file":"kuca-fudbala-0021.jpg","width":450,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021.jpg"}},"image_meta":{"aperture":"3","credit":"","camera":"Canon PowerShot A470","caption":"","created_timestamp":"1296825564","copyright":"","focal_length":"6.3","iso":"250","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-0021.jpg","_links":{"self":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media\/3101"}],"collection":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/comments?post=3101"}]}}