{"id":3104,"date":"2011-09-01T00:00:00","date_gmt":"2011-09-01T00:00:00","guid":{"rendered":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300.jpg"},"modified":"2011-09-01T00:00:00","modified_gmt":"2011-09-01T00:00:00","slug":"kuca-fudbala-1-400x300","status":"inherit","type":"attachment","link":"https:\/\/mppjedinstvo.co.rs\/rs\/kuca-fudbala-1-400x300\/","title":{"rendered":"kuca-fudbala-1-400&#215;300"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-300x225.jpg 300w, https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":300,"file":"2011\/09\/kuca-fudbala-1-400x300.jpg","filesize":47565,"sizes":{"medium":{"file":"kuca-fudbala-1-400x300-300x225.jpg","width":300,"height":225,"filesize":19419,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-300x225.jpg"},"thumbnail":{"file":"kuca-fudbala-1-400x300-150x150.jpg","width":150,"height":150,"filesize":7581,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-150x150.jpg"},"post-thumbnail":{"file":"kuca-fudbala-1-400x300-400x288.jpg","width":400,"height":288,"filesize":33551,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-400x288.jpg"},"large-feature":{"file":"kuca-fudbala-1-400x300-400x288.jpg","width":400,"height":288,"filesize":33551,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300-400x288.jpg"},"full":{"file":"kuca-fudbala-1-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/kuca-fudbala-1-400x300.jpg","_links":{"self":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media\/3104"}],"collection":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/comments?post=3104"}]}}