{"id":3284,"date":"2011-09-01T00:00:00","date_gmt":"2011-09-01T00:00:00","guid":{"rendered":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006.jpg"},"modified":"2011-09-01T00:00:00","modified_gmt":"2011-09-01T00:00:00","slug":"sabac-0006","status":"inherit","type":"attachment","link":"https:\/\/mppjedinstvo.co.rs\/rs\/sabac-0006\/","title":{"rendered":"sabac-0006"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-300x225.jpg 300w, https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-768x576.jpg 768w, https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-400x300.jpg 400w, https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2011\/09\/sabac-0006.jpg","filesize":117762,"sizes":{"medium":{"file":"sabac-0006-300x225.jpg","width":300,"height":225,"filesize":27454,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-300x225.jpg"},"thumbnail":{"file":"sabac-0006-150x150.jpg","width":150,"height":150,"filesize":20568,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-150x150.jpg"},"medium_large":{"file":"sabac-0006-768x576.jpg","width":768,"height":576,"filesize":74811,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-768x576.jpg"},"post-thumbnail":{"file":"sabac-0006-800x288.jpg","width":800,"height":288,"filesize":56104,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-800x288.jpg"},"large-feature":{"file":"sabac-0006-800x288.jpg","width":800,"height":288,"filesize":56104,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-800x288.jpg"},"small-feature":{"file":"sabac-0006-400x300.jpg","width":400,"height":300,"filesize":34328,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006-400x300.jpg"},"full":{"file":"sabac-0006.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006.jpg"}},"image_meta":{"aperture":"7.1","credit":"","camera":"DSC-W35","caption":"","created_timestamp":"1227296659","copyright":"","focal_length":"6.3","iso":"100","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-content\/uploads\/sites\/2\/2011\/09\/sabac-0006.jpg","_links":{"self":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media\/3284"}],"collection":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/comments?post=3284"}]}}