{"id":986,"date":"2012-04-10T01:08:04","date_gmt":"2012-04-09T23:08:04","guid":{"rendered":"https:\/\/mppjedinstvo.co.rs\/rs\/?p=986"},"modified":"2012-04-10T01:08:04","modified_gmt":"2012-04-09T23:08:04","slug":"merkator-beograd","status":"publish","type":"post","link":"https:\/\/mppjedinstvo.co.rs\/rs\/2012\/04\/10\/merkator-beograd\/","title":{"rendered":"MERKATOR Beograd"},"content":{"rendered":"<p>Izvo\u0111enje radova na ma\u0161inskim instalacijama; <br \/>\nVrednost ugovora: 760.738,73 eur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Izvo\u0111enje radova na ma\u0161inskim instalacijama; Vrednost ugovora: 760.738,73 eur<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/posts\/986"}],"collection":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/comments?post=986"}],"version-history":[{"count":0,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/posts\/986\/revisions"}],"wp:attachment":[{"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/media?parent=986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/categories?post=986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mppjedinstvo.co.rs\/rs\/wp-json\/wp\/v2\/tags?post=986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}